{"id":942,"date":"2024-08-09T05:32:49","date_gmt":"2024-08-09T03:32:49","guid":{"rendered":"https:\/\/thewebdesign.nl\/cart\/"},"modified":"2024-10-28T09:26:00","modified_gmt":"2024-10-28T08:26:00","slug":"cart","status":"publish","type":"page","link":"https:\/\/thewebdesign.nl\/en\/cart\/","title":{"rendered":"Cart"},"content":{"rendered":"\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-942","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/thewebdesign.nl\/en\/wp-json\/wp\/v2\/pages\/942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thewebdesign.nl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/thewebdesign.nl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/thewebdesign.nl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thewebdesign.nl\/en\/wp-json\/wp\/v2\/comments?post=942"}],"version-history":[{"count":1,"href":"https:\/\/thewebdesign.nl\/en\/wp-json\/wp\/v2\/pages\/942\/revisions"}],"predecessor-version":[{"id":2365,"href":"https:\/\/thewebdesign.nl\/en\/wp-json\/wp\/v2\/pages\/942\/revisions\/2365"}],"wp:attachment":[{"href":"https:\/\/thewebdesign.nl\/en\/wp-json\/wp\/v2\/media?parent=942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}